{"id":26888,"date":"2021-04-14T05:08:44","date_gmt":"2021-04-14T03:08:44","guid":{"rendered":"https:\/\/mancomun.gal\/pildora-sobre-zabbix-solucion-de-monitorizacion-de-redes\/"},"modified":"2022-09-08T07:37:18","modified_gmt":"2022-09-08T05:37:18","slug":"pildora-sobre-zabbix-solucion-de-monitorizacion-de-redes","status":"publish","type":"post","link":"https:\/\/mancomun.gal\/es\/pildora-sobre-zabbix-solucion-de-monitorizacion-de-redes\/","title":{"rendered":"P\u00edldora sobre Zabbix, soluci\u00f3n de monitorizaci\u00f3n de redes"},"content":{"rendered":"<p><a href=\"https:\/\/www.zabbix.com\/\">Zabbix<\/a> es una herramienta de software libre para monitorizaci\u00f3n de redes. La gesti\u00f3n de una red de ordenadores dentro de una empresa es uno de los aspectos principales a tener en cuenta. <strong>La conectividad y el acceso a la informaci\u00f3n, son aspectos clave en la organizaci\u00f3n de las empresas modernas<\/strong> en cualquier \u00e1mbito de actividad.<\/p>\n<h2>P\u00edldora sobre Zabbix, soluci\u00f3n de monitorizaci\u00f3n de redes<\/h2>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-26888-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.mancomun.gal\/wp-content\/uploads\/2021\/04\/P\u00edlula-sobre-Zabbix-soluci\u00f3n-de-monitorizaci\u00f3n-de-redes.mp4?_=1\" \/><a href=\"https:\/\/www.mancomun.gal\/wp-content\/uploads\/2021\/04\/P\u00edlula-sobre-Zabbix-soluci\u00f3n-de-monitorizaci\u00f3n-de-redes.mp4\">https:\/\/www.mancomun.gal\/wp-content\/uploads\/2021\/04\/P\u00edlula-sobre-Zabbix-soluci\u00f3n-de-monitorizaci\u00f3n-de-redes.mp4<\/a><\/video><\/div>\n<p><strong>Zabbix<\/strong><\/p>\n<p>Zabbix permite monitorizar y registrar el estado de varios servicios en una red de ordenadores, servidores o hardware de la propia red interna de una organizaci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-27442\" src=\"https:\/\/mancomun.gal\/wp-content\/uploads\/2022\/09\/portada-logo-7.png\" alt=\"\" width=\"1920\" height=\"1080\" \/><\/p>\n<p><strong>Entre sus caracter\u00edsticas destacan:<br \/>\n<\/strong>&#8211; Colecci\u00f3n inteligente y altamente automatizada de m\u00e9tricas<br \/>\n&#8211; Descubrimiento autom\u00e1tico<br \/>\n&#8211; Detecci\u00f3n avanzada de problemas<br \/>\n&#8211; Verificaci\u00f3n de la disponibilidad y nivel de respuesta de varios servicios como por ejemplo servicios web o de correo<br \/>\n&#8211; Estad\u00edsticas como carga de la CPU, uso de disco, ancho de banda de la red&#8230;<br \/>\n&#8211; Permite monitorizar servicios a trav\u00e9s de diferentes protocolos<br \/>\n&#8211; Zabbix est\u00e1 disponible bajo la licencia de software Libre GPL<br \/>\n&#8211; Predicci\u00f3n de tendencias<\/p>\n<p>Podemos descargarlo libremente desde <a href=\"https:\/\/www.zabbix.com\/la\/download\">la web<\/a> oficial, e instalarlo en el servidor de nuestra empresa. Tambi\u00e9n podemos probar Zabbix a trav\u00e9s del <a href=\"https:\/\/cdtic.xunta.gal\/app-ficha\/8298\">CDTIC Virtual<\/a>, sin necesidad de instalar nada.<\/p>\n<p>Esperamos que esta p\u00edldora os ayude en vuestro trabajo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zabbix es una herramienta de software libre para monitorizaci\u00f3n de redes. La gesti\u00f3n de una red de ordenadores dentro de una empresa es uno de los aspectos principales a tener en cuenta. La conectividad y el acceso a la informaci\u00f3n, son aspectos clave en la organizaci\u00f3n de las empresas modernas en cualquier \u00e1mbito de actividad. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-26888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/posts\/26888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/comments?post=26888"}],"version-history":[{"count":1,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/posts\/26888\/revisions"}],"predecessor-version":[{"id":26889,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/posts\/26888\/revisions\/26889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/media\/21487"}],"wp:attachment":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/media?parent=26888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/categories?post=26888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/tags?post=26888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}