{"id":26915,"date":"2021-04-15T07:32:16","date_gmt":"2021-04-15T05:32:16","guid":{"rendered":"https:\/\/mancomun.gal\/proxmox-mail-gateway-6-4-integracion-con-proxmox-backup\/"},"modified":"2021-04-15T07:32:16","modified_gmt":"2021-04-15T05:32:16","slug":"proxmox-mail-gateway-6-4-integracion-con-proxmox-backup","status":"publish","type":"post","link":"https:\/\/mancomun.gal\/es\/proxmox-mail-gateway-6-4-integracion-con-proxmox-backup\/","title":{"rendered":"Proxmox Mail Gateway 6.4, integraci\u00f3n con Proxmox Backup"},"content":{"rendered":"<p><a href=\"https:\/\/www.proxmox.com\/en\/\">Proxmox<\/a> lanz\u00f3 la nueva versi\u00f3n de la distribuci\u00f3n Proxmox Mail Gateway 6.4., <strong>soluci\u00f3n para crear r\u00e1pidamente un sistema de control de tr\u00e1fico de correo y proteger el servidor de correo interno<\/strong>.<\/p>\n<p>Es posible gestionar todos los flujos de correo entrantes y salientes. Todos los registros de correspondencia se analizan y est\u00e1n disponibles para su an\u00e1lisis a trav\u00e9s de la interfaz web. Destaca tambi\u00e9n la integraci\u00f3n mejorada con la infraestructura de respaldo basada en Proxmox Backup Server, agregando la capacidad de recibir notificaciones por correo electr\u00f3nico sobre respaldos.<\/p>\n<p><strong>Otras novedades:<\/strong> configurable desde la GUI, gesti\u00f3n general de certificados a trav\u00e9s de la GUI, gesti\u00f3n de cuarentena mejorada (la cuarentena de spam ahora puede procesar grandes cantidades de correos a la vez), mejoras en el registro de TLS en el centro de seguimiento, entre otras.<\/p>\n<p><a href=\"https:\/\/forum.proxmox.com\/threads\/proxmox-mail-gateway-6-4-released.86760\/\">M\u00e1s informaci\u00f3n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proxmox lanz\u00f3 la nueva versi\u00f3n de la distribuci\u00f3n Proxmox Mail Gateway 6.4., soluci\u00f3n para crear r\u00e1pidamente un sistema de control de tr\u00e1fico de correo y proteger el servidor de correo interno. Es posible gestionar todos los flujos de correo entrantes y salientes. Todos los registros de correspondencia se analizan y est\u00e1n disponibles para su an\u00e1lisis [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-26915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/posts\/26915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/comments?post=26915"}],"version-history":[{"count":0,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/posts\/26915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/media\/21521"}],"wp:attachment":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/media?parent=26915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/categories?post=26915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/tags?post=26915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}