{"id":35298,"date":"2006-12-04T09:51:52","date_gmt":"2006-12-04T08:51:52","guid":{"rendered":"https:\/\/mancomun.gal\/xbmc-un-media-center-gpl-para-a-tua-consola-xbox\/"},"modified":"2023-05-09T16:29:44","modified_gmt":"2023-05-09T14:29:44","slug":"xbmc-un-media-center-gpl-para-a-tua-consola-xbox","status":"publish","type":"post","link":"https:\/\/mancomun.gal\/es\/xbmc-un-media-center-gpl-para-a-tua-consola-xbox\/","title":{"rendered":"XBMC &#8211; Un media center GPL para a t\u00faa consola XBOX"},"content":{"rendered":"<div align=\"justify\"><a title=\"http:\/\/sourceforge.net\/projects\/xbmc\" target=\"_blank\" href=\"http:\/\/sourceforge.net\/projects\/xbmc\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"140\" vspace=\"5\" hspace=\"10\" height=\"93\" border=\"0\" align=\"left\" title=\"http:\/\/www.mancomun.org\/images\/stories\/xboxmediacenter.jpg\" alt=\"http:\/\/www.mancomun.org\/images\/stories\/xboxmediacenter.jpg\" src=\"https:\/\/mancomun.gal\/wp-content\/uploads\/2022\/09\/xboxmediacenter.jpg\" \/><\/a> <a title=\"http:\/\/www.xboxmediacenter.com\/\" target=\"_blank\" href=\"http:\/\/www.xboxmediacenter.com\/\" rel=\"noopener\">XboxMediaCenter<\/a>  \u00e9 un reprodutor multimedia baseado en Software Libre para a consola XBOX de Microsoft. Actualmente o software <a title=\"http:\/\/www.xboxmediacenter.com\/\" target=\"_blank\" href=\"http:\/\/www.xboxmediacenter.com\/\" rel=\"noopener\">XboxMediaCenter<\/a> (XBMC)  pode reproducir videos\/ver imaxes na maior\u00eda dos formatos de audio\/v\u00eddeo\/imaxe coma son os formatos MPEG-1\/2\/4, DivX, [[XviD]], MP3, AAC, JPG, GIF ademais de outros moitos formatos menos co\u00f1ecidos directamente dende o lector de CD\/DVD da consola ou do seu disco duro. <\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">XBMC ademais tam\u00e9n pode facer <a title=\"http:\/\/www.google.es\/search?hl=es&#038;q=define%3A+streaming&#038;btnG=B%C3%BAsqueda+en+Google&#038;meta=\" target=\"_blank\" href=\"http:\/\/www.google.es\/search?hl=es&#038;q=define%3A+streaming&#038;btnG=B%C3%BAsqueda+en+Google&#038;meta=\" rel=\"noopener\">streaming<\/a>  de ficheiros dun PC sobre unha rede local de computadores e incluso directamente cara internet&#8230;<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<p><\/p>\n<div align=\"justify\">XBMC ten listas de reproduci\u00f3n e funci\u00f3ns de presentaci\u00f3n e at\u00e9 informaci\u00f3n meteorol\u00f3xica. <\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">Todas estas caracter\u00edsticas permiten ao XBMC facer funcionar \u00e1 XBOX coma un mediacenter real. <\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><a title=\"http:\/\/sourceforge.net\/forum\/forum.php?forum_id=633054\" target=\"_blank\" href=\"http:\/\/sourceforge.net\/forum\/forum.php?forum_id=633054\" rel=\"noopener\">A versi\u00f3n actual deste software \u00e9 a 2.0.1<\/a>  que podes descargar dende <a title=\"http:\/\/sourceforge.net\/projects\/xbmc\" target=\"_blank\" href=\"http:\/\/sourceforge.net\/projects\/xbmc\" rel=\"noopener\">SourceForge<\/a>. <\/div>\n","protected":false},"excerpt":{"rendered":"<div align=\"justify\"><a title=\"http:\/\/sourceforge.net\/projects\/xbmc\" target=\"_blank\" href=\"http:\/\/sourceforge.net\/projects\/xbmc\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"140\" vspace=\"5\" hspace=\"10\" height=\"93\" border=\"0\" align=\"left\" title=\"http:\/\/www.mancomun.org\/images\/stories\/xboxmediacenter.jpg\" alt=\"http:\/\/www.mancomun.org\/images\/stories\/xboxmediacenter.jpg\" src=\"https:\/\/www.mancomun.gal\/wp-content\/uploads\/uploads\/pics\/stories\/xboxmediacenter.jpg\" \/><\/a> <a title=\"http:\/\/www.xboxmediacenter.com\/\" target=\"_blank\" href=\"http:\/\/www.xboxmediacenter.com\/\" rel=\"noopener\">XboxMediaCenter<\/a>  \u00e9 un reprodutor multimedia baseado en Software Libre para a consola XBOX de Microsoft. Actualmente o software <a title=\"http:\/\/www.xboxmediacenter.com\/\" target=\"_blank\" href=\"http:\/\/www.xboxmediacenter.com\/\" rel=\"noopener\">XboxMediaCenter<\/a> (XBMC)  pode reproducir videos\/ver imaxes na maior\u00eda dos formatos de audio\/v\u00eddeo\/imaxe coma son os formatos MPEG-1\/2\/4, DivX, [[XviD]], MP3, AAC, JPG, GIF ademais de outros moitos formatos menos co\u00f1ecidos directamente dende o lector de CD\/DVD da consola ou do seu disco duro. <\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">XBMC ademais tam\u00e9n pode facer <a title=\"http:\/\/www.google.es\/search?hl=es&#038;q=define%3A+streaming&#038;btnG=B%C3%BAsqueda+en+Google&#038;meta=\" target=\"_blank\" href=\"http:\/\/www.google.es\/search?hl=es&#038;q=define%3A+streaming&#038;btnG=B%C3%BAsqueda+en+Google&#038;meta=\" rel=\"noopener\">streaming<\/a>  de ficheiros dun PC sobre unha rede local de computadores e incluso directamente cara internet&#8230;<\/div>\n<div align=\"justify\">\u00a0<\/div>\n","protected":false},"author":5,"featured_media":1046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-35298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/posts\/35298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/comments?post=35298"}],"version-history":[{"count":1,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/posts\/35298\/revisions"}],"predecessor-version":[{"id":35299,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/posts\/35298\/revisions\/35299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/media\/1046"}],"wp:attachment":[{"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/media?parent=35298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/categories?post=35298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mancomun.gal\/es\/wp-json\/wp\/v2\/tags?post=35298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}